{"id":15028,"date":"2026-04-16T13:41:38","date_gmt":"2026-04-16T11:41:38","guid":{"rendered":"https:\/\/www.ccoo.cat\/lleida\/?p=15028"},"modified":"2026-04-17T09:35:46","modified_gmt":"2026-04-17T07:35:46","slug":"assemblea-de-delegats-i-delegades-de-ccoo-per-reclamar-salaris-sostre-i-drets","status":"publish","type":"post","link":"https:\/\/www.ccoo.cat\/lleida\/noticies\/assemblea-de-delegats-i-delegades-de-ccoo-per-reclamar-salaris-sostre-i-drets\/","title":{"rendered":"Assemblea de delegats i delegades de CCOO per reclamar salaris, sostre i drets"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 16 d\u2019abril, 140 delegats i delegades de CCOO de Lleida van assistir, a Cornell\u00e0, a l\u2019assemblea que havia convocat CCOO de Catalunya amb el lema: \u201cSalaris, sostre i drets\u201d. Aquesta assemblea assenyala el cam\u00ed del proper cicle d\u2019eleccions sindicals i s\u2019ha centrat en la lluita pel treball digne, l\u2019habitatge i la millora salarial. A l\u2019assemblea, hi van intervenir Bel\u00e9n L\u00f3pez, secret\u00e0ria general de CCOO de Catalunya, i Unai Sordo, secretari general de CCOO d\u2019Espanya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CCOO va reivindicar que per garantir salaris justos i millors condicions laborals cal exigir la redistribuci\u00f3 de la riquesa i el poder empresarial. Per a CCOO l\u2019habitatge \u00e9s un dret fonamental per a la classe treballadora i per aix\u00f2 l\u2019inclou com un pilar de les seves reclamacions, a les quals s\u2019afegeixen tamb\u00e9 les accions per equiparar drets, organitzar el temps per viure millor i conquerir nous drets laborals.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019assemblea tamb\u00e9 va fer \u00e8mfasi en la necessitat d\u2019aturar l\u2019onada reaccionaria que sacseja el m\u00f3n i el nostre pa\u00eds, i que per fer-ho cal refor\u00e7ar les organitzacions de classe i les pol\u00edtiques p\u00fabliques que garanteixen els drets de les persones. Assemblees com la que es va fer a &nbsp;Cornell\u00e0 mostren que hi ha alternatives reals a l\u2019auge de l\u2019extrema dreta que amena\u00e7a la pau i la democr\u00e0cia, i que el sindicalisme de classe n\u2019\u00e9s un baluard clau per posar-hi fre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 16 d\u2019abril, 140 delegats i delegades de CCOO de Lleida van assistir, a Cornell\u00e0, a l\u2019assemblea que havia convocat &#8230; <a title=\"Assemblea de delegats i delegades de CCOO per reclamar salaris, sostre i drets\" class=\"read-more\" href=\"https:\/\/www.ccoo.cat\/lleida\/noticies\/assemblea-de-delegats-i-delegades-de-ccoo-per-reclamar-salaris-sostre-i-drets\/\" aria-label=\"M\u00e9s informaci\u00f3 sobre Assemblea de delegats i delegades de CCOO per reclamar salaris, sostre i drets\">Llegiu-me m\u00e9s<\/a><\/p>\n","protected":false},"author":504,"featured_media":15029,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ccoo_send_notification":1,"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-15028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.ccoo.cat\/lleida\/wp-json\/wp\/v2\/posts\/15028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ccoo.cat\/lleida\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccoo.cat\/lleida\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccoo.cat\/lleida\/wp-json\/wp\/v2\/users\/504"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccoo.cat\/lleida\/wp-json\/wp\/v2\/comments?post=15028"}],"version-history":[{"count":2,"href":"https:\/\/www.ccoo.cat\/lleida\/wp-json\/wp\/v2\/posts\/15028\/revisions"}],"predecessor-version":[{"id":15034,"href":"https:\/\/www.ccoo.cat\/lleida\/wp-json\/wp\/v2\/posts\/15028\/revisions\/15034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ccoo.cat\/lleida\/wp-json\/wp\/v2\/media\/15029"}],"wp:attachment":[{"href":"https:\/\/www.ccoo.cat\/lleida\/wp-json\/wp\/v2\/media?parent=15028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccoo.cat\/lleida\/wp-json\/wp\/v2\/categories?post=15028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ccoo.cat\/lleida\/wp-json\/wp\/v2\/tags?post=15028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}