{"id":5103,"date":"2023-09-04T12:57:17","date_gmt":"2023-09-04T10:57:17","guid":{"rendered":"https:\/\/www.ccoo.cat\/industria\/?page_id=5103"},"modified":"2026-04-28T11:07:06","modified_gmt":"2026-04-28T09:07:06","slug":"conveni-de-la-industria-siderometallurgica-de-lleida","status":"publish","type":"page","link":"https:\/\/www.ccoo.cat\/industria\/conveni-de-la-industria-siderometallurgica-de-lleida\/","title":{"rendered":"Conveni de la ind\u00fastria siderometal\u00b7l\u00fargica de Lleida"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"279\" src=\"https:\/\/www.ccoo.cat\/industria\/wp-content\/uploads\/sites\/109\/2023\/09\/metall-detall-soldador-conveni.jpg\" alt=\"Metall Detall Soldador Conveni\" class=\"wp-image-5117\" srcset=\"https:\/\/www.ccoo.cat\/industria\/wp-content\/uploads\/sites\/109\/2023\/09\/metall-detall-soldador-conveni.jpg 1024w, https:\/\/www.ccoo.cat\/industria\/wp-content\/uploads\/sites\/109\/2023\/09\/metall-detall-soldador-conveni-300x82.jpg 300w, https:\/\/www.ccoo.cat\/industria\/wp-content\/uploads\/sites\/109\/2023\/09\/metall-detall-soldador-conveni-768x209.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>5 de setembre de 2025<\/strong> CCOO d&#8217;Ind\u00fastria de Catalunya, UGT-FICA i la patronal FEMELL vam signar el Conveni col\u00b7lectiu per a la ind\u00fastria siderometal\u00b7l\u00fargica de la prov\u00edncia de Lleida per als anys 2025-2027, en els termes del preacord assolit el <strong>25 de juliol de 2025<\/strong>, despr\u00e9s que aquest fos ratificat pels delegats i delegades i l&#8217;afiliaci\u00f3 del sector. Amb aquest conveni es garanteix el poder adquisitiu i es milloren els drets i les condicions de les prop de 13.000 persones que treballen al sector en aquesta prov\u00edncia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El text del conveni i les taules salarials del primer any s&#8217;han publicat al <strong>BOP de Lleida n\u00famero 236, d&#8217;11 de desembre de 2025<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;<strong>11 de febrer de 2026<\/strong> es va signar la revisi\u00f3 de les taules salarials de 2026 amb un increment d&#8217;un 2,5 % i d&#8217;un 4,5 % d&#8217;increment per a les pagues extraordin\u00e0ries. Les taules de 2026 s&#8217;han publicat al <strong>BOP de LLeida n\u00famero 40, de 6 de mar\u00e7 de 2026<\/strong>.<\/p>\n\n\n\n<div id=\"section-gc158c6\" class=\"wp-block-gutentor-e2 section-gc158c6 gutentor-element gutentor-element-button\"><span class=\"gutentor-button-wrap\"><a class=\"gutentor-button gutentor-block-button gutentor-icon-hide\" href=\"https:\/\/ebop.diputaciolleida.cat\/aplicacions\/bop\/bopV1\/fitxers\/pdf\/2025\/236\/2025236010098.pdf\" target=\"_blank\" rel=\" noopener noreferrer\"><i class=\"gutentor-button-icon fas fa-book\"><\/i><span>Conveni de la ind\u00fastria siderometal\u00b7l\u00fargica de Lleida \u00bb<\/span><\/a><\/span><\/div>\n\n\n\n<div id=\"section-g-4ttv1sc\" class=\"wp-block-gutentor-e2 section-g-4ttv1sc gutentor-element gutentor-element-button\"><span class=\"gutentor-button-wrap\"><a class=\"gutentor-button gutentor-block-button gutentor-icon-hide\" href=\"https:\/\/calculadoralleida.ccoo.cat\/\" target=\"_blank\" rel=\" noopener noreferrer\"><i class=\"gutentor-button-icon fas fa-book\"><\/i><span>CALCULADORA D&#8217;INCREMENTS SALARIALS<\/span><\/a><\/span><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">DOCUMENTS VIGENTS:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/ebop.diputaciolleida.cat\/aplicacions\/bop\/bopV1\/fitxers\/pdf\/2025\/236\/2025236010098.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Publicaci\u00f3 al BOP del conveni 2025-2027<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.ccoo.cat\/industria\/wp-content\/uploads\/sites\/109\/2026\/04\/taules-salarials-2025-conveni-metall-lleida.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Taules salarials 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.ccoo.cat\/industria\/wp-content\/uploads\/sites\/109\/2026\/04\/taules-salarials-2026-conveni-metall-lleida.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Taules salarials 2026<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/ebop.diputaciolleida.cat\/aplicacions\/bop\/bopV1\/fitxers\/pdf\/2026\/45\/20264501625.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Publicaci\u00f3 al BOP de les taules salarials de 2026<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.ccoo.cat\/industria\/wp-content\/uploads\/sites\/109\/2026\/04\/cartell-novetats-conveni-metall-lleida-2025-2027.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Cartell resum novetats conveni 2025-2027<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/ccoo.app\/convenio\/convenio-colectivo-industrias-siderometalurgicas-de-lleida\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fitxa resum del conveni<\/a><\/li>\n<\/ul>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"actualitat-sobre-el-sector\">Actualitat sobre el sector<\/h2>\n\n\n<div class=\"wpblock-ccoonews\"><a href=\"https:\/\/www.ccoo.cat\/industria\/convenis\/comunicat-conveni-del-metall-de-lleida\/\"><div class=\"item-post\"><div class=\"title\"><h3 class=\"widget-title\">COMUNICAT. Conveni del metall de Lleida<\/h3><div class=\"post-date\">12\/02\/2026<\/div><\/div><div class=\"arrow\"><svg width=\"51\" height=\"24\" viewBox=\"0 0 51 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<rect x=\"50.2922\" y=\"11.7348\" width=\"1.7781\" height=\"16.5956\" transform=\"rotate(135 50.2922 11.7348)\" fill=\"black\"\/>\n\t\t\t\t<rect x=\"49.0349\" y=\"10.4775\" width=\"1.7781\" height=\"16.5956\" transform=\"rotate(45 49.0349 10.4775)\" fill=\"black\"\/>\n\t\t\t\t<rect x=\"47.7267\" y=\"10.8458\" width=\"1.7781\" height=\"47.7267\" transform=\"rotate(90 47.7267 10.8458)\" fill=\"black\"\/>\n\t\t\t\t<\/svg><\/div><div class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"297\" height=\"160\" src=\"https:\/\/www.ccoo.cat\/industria\/wp-content\/uploads\/sites\/109\/2026\/02\/signatura-taules-2026-conveni-metall-lleida-e1770906698802-297x160.jpeg\" class=\"attachment-news-block size-news-block wp-post-image\" alt=\"Signatura Taules 2026 Conveni Metall Lleida\" \/><\/div><\/div><\/a><a href=\"https:\/\/www.ccoo.cat\/industria\/noticies\/signat-el-conveni-del-metall-de-lleida-per-als-anys-2025-2027\/\"><div class=\"item-post\"><div class=\"title\"><h3 class=\"widget-title\">Signat el Conveni del metall de Lleida per als anys 2025-2027<\/h3><div class=\"post-date\">05\/09\/2025<\/div><\/div><div class=\"arrow\"><svg width=\"51\" height=\"24\" viewBox=\"0 0 51 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<rect x=\"50.2922\" y=\"11.7348\" width=\"1.7781\" height=\"16.5956\" transform=\"rotate(135 50.2922 11.7348)\" fill=\"black\"\/>\n\t\t\t\t<rect x=\"49.0349\" y=\"10.4775\" width=\"1.7781\" height=\"16.5956\" transform=\"rotate(45 49.0349 10.4775)\" fill=\"black\"\/>\n\t\t\t\t<rect x=\"47.7267\" y=\"10.8458\" width=\"1.7781\" height=\"47.7267\" transform=\"rotate(90 47.7267 10.8458)\" fill=\"black\"\/>\n\t\t\t\t<\/svg><\/div><div class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"297\" height=\"160\" src=\"https:\/\/www.ccoo.cat\/industria\/wp-content\/uploads\/sites\/109\/2025\/09\/003-297x160.jpeg\" class=\"attachment-news-block size-news-block wp-post-image\" alt=\"003\" \/><\/div><\/div><\/a><a href=\"https:\/\/www.ccoo.cat\/industria\/convenis\/comunicat-10-conveni-del-metall-de-lleida\/\"><div class=\"item-post\"><div class=\"title\"><h3 class=\"widget-title\">COMUNICAT 10. Conveni del metall de Lleida<\/h3><div class=\"post-date\">05\/09\/2025<\/div><\/div><div class=\"arrow\"><svg width=\"51\" height=\"24\" viewBox=\"0 0 51 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<rect x=\"50.2922\" y=\"11.7348\" width=\"1.7781\" height=\"16.5956\" transform=\"rotate(135 50.2922 11.7348)\" fill=\"black\"\/>\n\t\t\t\t<rect x=\"49.0349\" y=\"10.4775\" width=\"1.7781\" height=\"16.5956\" transform=\"rotate(45 49.0349 10.4775)\" fill=\"black\"\/>\n\t\t\t\t<rect x=\"47.7267\" y=\"10.8458\" width=\"1.7781\" height=\"47.7267\" transform=\"rotate(90 47.7267 10.8458)\" fill=\"black\"\/>\n\t\t\t\t<\/svg><\/div><div class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"297\" height=\"160\" src=\"https:\/\/www.ccoo.cat\/industria\/wp-content\/uploads\/sites\/109\/2022\/10\/metall4-297x160.jpg\" class=\"attachment-news-block size-news-block wp-post-image\" alt=\"Steel Production In Electric Furnaces\" \/><\/div><\/div><\/a><a href=\"https:\/\/www.ccoo.cat\/industria\/convenis\/comunicat-9-conveni-del-metall-de-lleida\/\"><div class=\"item-post\"><div class=\"title\"><h3 class=\"widget-title\">COMUNICAT 9. Conveni del metall de Lleida<\/h3><div class=\"post-date\">28\/07\/2025<\/div><\/div><div class=\"arrow\"><svg width=\"51\" height=\"24\" viewBox=\"0 0 51 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<rect x=\"50.2922\" y=\"11.7348\" width=\"1.7781\" height=\"16.5956\" transform=\"rotate(135 50.2922 11.7348)\" fill=\"black\"\/>\n\t\t\t\t<rect x=\"49.0349\" y=\"10.4775\" width=\"1.7781\" height=\"16.5956\" transform=\"rotate(45 49.0349 10.4775)\" fill=\"black\"\/>\n\t\t\t\t<rect x=\"47.7267\" y=\"10.8458\" width=\"1.7781\" height=\"47.7267\" transform=\"rotate(90 47.7267 10.8458)\" fill=\"black\"\/>\n\t\t\t\t<\/svg><\/div><div class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"297\" height=\"160\" src=\"https:\/\/www.ccoo.cat\/industria\/wp-content\/uploads\/sites\/109\/2022\/10\/metall4-297x160.jpg\" class=\"attachment-news-block size-news-block wp-post-image\" alt=\"Steel Production In Electric Furnaces\" \/><\/div><\/div><\/a><a href=\"https:\/\/www.ccoo.cat\/industria\/convenis\/comunicat-8-conveni-del-metall-de-lleida\/\"><div class=\"item-post\"><div class=\"title\"><h3 class=\"widget-title\">COMUNICAT 8. Conveni del metall de Lleida<\/h3><div class=\"post-date\">10\/07\/2025<\/div><\/div><div class=\"arrow\"><svg width=\"51\" height=\"24\" viewBox=\"0 0 51 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<rect x=\"50.2922\" y=\"11.7348\" width=\"1.7781\" height=\"16.5956\" transform=\"rotate(135 50.2922 11.7348)\" fill=\"black\"\/>\n\t\t\t\t<rect x=\"49.0349\" y=\"10.4775\" width=\"1.7781\" height=\"16.5956\" transform=\"rotate(45 49.0349 10.4775)\" fill=\"black\"\/>\n\t\t\t\t<rect x=\"47.7267\" y=\"10.8458\" width=\"1.7781\" height=\"47.7267\" transform=\"rotate(90 47.7267 10.8458)\" fill=\"black\"\/>\n\t\t\t\t<\/svg><\/div><div class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"297\" height=\"160\" src=\"https:\/\/www.ccoo.cat\/industria\/wp-content\/uploads\/sites\/109\/2022\/10\/metall4-297x160.jpg\" class=\"attachment-news-block size-news-block wp-post-image\" alt=\"Steel Production In Electric Furnaces\" \/><\/div><\/div><\/a><a href=\"https:\/\/www.ccoo.cat\/industria\/convenis\/comunicat-7-conveni-del-metall-de-lleida-2\/\"><div class=\"item-post\"><div class=\"title\"><h3 class=\"widget-title\">COMUNICAT 7. Conveni del metall de Lleida<\/h3><div class=\"post-date\">26\/06\/2025<\/div><\/div><div class=\"arrow\"><svg width=\"51\" height=\"24\" viewBox=\"0 0 51 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<rect x=\"50.2922\" y=\"11.7348\" width=\"1.7781\" height=\"16.5956\" transform=\"rotate(135 50.2922 11.7348)\" fill=\"black\"\/>\n\t\t\t\t<rect x=\"49.0349\" y=\"10.4775\" width=\"1.7781\" height=\"16.5956\" transform=\"rotate(45 49.0349 10.4775)\" fill=\"black\"\/>\n\t\t\t\t<rect x=\"47.7267\" y=\"10.8458\" width=\"1.7781\" height=\"47.7267\" transform=\"rotate(90 47.7267 10.8458)\" fill=\"black\"\/>\n\t\t\t\t<\/svg><\/div><div class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"297\" height=\"160\" src=\"https:\/\/www.ccoo.cat\/industria\/wp-content\/uploads\/sites\/109\/2022\/10\/metall4-297x160.jpg\" class=\"attachment-news-block size-news-block wp-post-image\" alt=\"Steel Production In Electric Furnaces\" \/><\/div><\/div><\/a><a href=\"https:\/\/www.ccoo.cat\/industria\/convenis\/comunicat-6-conveni-del-metall-de-lleida-2\/\"><div class=\"item-post\"><div class=\"title\"><h3 class=\"widget-title\">COMUNICAT 6. Conveni del metall de Lleida<\/h3><div class=\"post-date\">05\/06\/2025<\/div><\/div><div class=\"arrow\"><svg width=\"51\" height=\"24\" viewBox=\"0 0 51 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<rect x=\"50.2922\" y=\"11.7348\" width=\"1.7781\" height=\"16.5956\" transform=\"rotate(135 50.2922 11.7348)\" fill=\"black\"\/>\n\t\t\t\t<rect x=\"49.0349\" y=\"10.4775\" width=\"1.7781\" height=\"16.5956\" transform=\"rotate(45 49.0349 10.4775)\" fill=\"black\"\/>\n\t\t\t\t<rect x=\"47.7267\" y=\"10.8458\" width=\"1.7781\" height=\"47.7267\" transform=\"rotate(90 47.7267 10.8458)\" fill=\"black\"\/>\n\t\t\t\t<\/svg><\/div><div class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"297\" height=\"160\" src=\"https:\/\/www.ccoo.cat\/industria\/wp-content\/uploads\/sites\/109\/2022\/10\/metall4-297x160.jpg\" class=\"attachment-news-block size-news-block wp-post-image\" alt=\"Steel Production In Electric Furnaces\" \/><\/div><\/div><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El 5 de setembre de 2025 CCOO d&#8217;Ind\u00fastria de Catalunya, UGT-FICA i la patronal FEMELL vam signar el Conveni col\u00b7lectiu &#8230; <a title=\"COMUNICAT 6. Conveni del metall de Lleida\" class=\"read-more\" href=\"https:\/\/www.ccoo.cat\/industria\/convenis\/comunicat-6-conveni-del-metall-de-lleida-2\/\" aria-label=\"M\u00e9s informaci\u00f3 sobre COMUNICAT 6. Conveni del metall de Lleida\">Llegiu-me m\u00e9s<\/a><\/p>\n","protected":false},"author":2057,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ccoo_send_notification":1,"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"class_list":["post-5103","page","type-page","status-publish","hentry","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"_links":{"self":[{"href":"https:\/\/www.ccoo.cat\/industria\/wp-json\/wp\/v2\/pages\/5103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ccoo.cat\/industria\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ccoo.cat\/industria\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccoo.cat\/industria\/wp-json\/wp\/v2\/users\/2057"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccoo.cat\/industria\/wp-json\/wp\/v2\/comments?post=5103"}],"version-history":[{"count":5,"href":"https:\/\/www.ccoo.cat\/industria\/wp-json\/wp\/v2\/pages\/5103\/revisions"}],"predecessor-version":[{"id":19522,"href":"https:\/\/www.ccoo.cat\/industria\/wp-json\/wp\/v2\/pages\/5103\/revisions\/19522"}],"wp:attachment":[{"href":"https:\/\/www.ccoo.cat\/industria\/wp-json\/wp\/v2\/media?parent=5103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}